{"id":189,"date":"2025-02-24T14:32:33","date_gmt":"2025-02-24T13:32:33","guid":{"rendered":"https:\/\/leonardocincinelli.com\/?page_id=189"},"modified":"2026-02-23T10:36:12","modified_gmt":"2026-02-23T09:36:12","slug":"music-for-media-2","status":"publish","type":"page","link":"https:\/\/leonardocincinelli.com\/de\/music-for-media-2\/","title":{"rendered":"Musik f\u00fcr Medien"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"189\" class=\"elementor elementor-189\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-587455ba e-flex e-con-boxed e-con e-parent\" data-id=\"587455ba\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-745b5964 e-flex e-con-boxed e-con e-parent\" data-id=\"745b5964\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2ff05253 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"2ff05253\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A selection of works created for films, commercials and audiovisual installations.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7d8bf76e e-con-full e-flex e-con e-child\" data-id=\"7d8bf76e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0c4e1ae elementor-widget elementor-widget-jet-listing-grid\" data-id=\"0c4e1ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns&quot;:3}\" data-widget_type=\"jet-listing-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-listing-grid jet-listing\"><div class=\"jet-listing-grid__items grid-col-desk-3 grid-col-tablet-3 grid-col-mobile-3 jet-listing-grid--224\" data-queried-id=\"189|WP_Post\" data-nav=\"{&quot;enabled&quot;:false,&quot;type&quot;:null,&quot;more_el&quot;:null,&quot;query&quot;:[],&quot;widget_settings&quot;:{&quot;lisitng_id&quot;:224,&quot;posts_num&quot;:16,&quot;columns&quot;:3,&quot;columns_tablet&quot;:3,&quot;columns_mobile&quot;:3,&quot;column_min_width&quot;:240,&quot;column_min_width_tablet&quot;:240,&quot;column_min_width_mobile&quot;:240,&quot;inline_columns_css&quot;:false,&quot;is_archive_template&quot;:&quot;&quot;,&quot;post_status&quot;:[&quot;publish&quot;],&quot;use_random_posts_num&quot;:&quot;&quot;,&quot;max_posts_num&quot;:9,&quot;not_found_message&quot;:&quot;No data was found&quot;,&quot;is_masonry&quot;:false,&quot;equal_columns_height&quot;:&quot;&quot;,&quot;use_load_more&quot;:&quot;&quot;,&quot;load_more_id&quot;:&quot;&quot;,&quot;load_more_type&quot;:&quot;click&quot;,&quot;load_more_offset&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;use_custom_post_types&quot;:&quot;&quot;,&quot;custom_post_types&quot;:[],&quot;hide_widget_if&quot;:&quot;&quot;,&quot;carousel_enabled&quot;:&quot;&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;arrows&quot;:&quot;true&quot;,&quot;arrow_icon&quot;:&quot;fa fa-angle-left&quot;,&quot;dots&quot;:&quot;&quot;,&quot;autoplay&quot;:&quot;true&quot;,&quot;pause_on_hover&quot;:&quot;true&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;true&quot;,&quot;center_mode&quot;:&quot;&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500,&quot;inject_alternative_items&quot;:&quot;&quot;,&quot;injection_items&quot;:[],&quot;scroll_slider_enabled&quot;:&quot;&quot;,&quot;scroll_slider_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;custom_query&quot;:false,&quot;custom_query_id&quot;:&quot;&quot;,&quot;_element_id&quot;:&quot;&quot;,&quot;collapse_first_last_gap&quot;:false,&quot;list_tag_selection&quot;:&quot;&quot;,&quot;list_items_wrapper_tag&quot;:&quot;div&quot;,&quot;list_item_tag&quot;:&quot;div&quot;,&quot;empty_items_wrapper_tag&quot;:&quot;div&quot;}}\" data-page=\"1\" data-pages=\"1\" data-listing-source=\"posts\" data-listing-id=\"224\" data-query-id=\"\"><div class=\"jet-listing-grid__item jet-listing-dynamic-post-2158\" data-post-id=\"2158\"  ><div class=\"jet-engine-listing-overlay-wrap jet-popup-target\" data-url=\"#\" data-popup-instance=\"1645\" data-popup-trigger-type=\"click-self\" data-popup-is-jet-engine=\"1\">\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"224\" class=\"elementor elementor-224\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b59a357 e-con-full e-flex e-con e-child\" data-id=\"b59a357\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-afd04b0 elementor-widget elementor-widget-image\" data-id=\"afd04b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/leonardocincinelli.com\/de\/leo-music-design\/ghd-pink-campaign\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1890\" height=\"1063\" src=\"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/ghd.png\" class=\"attachment-full size-full wp-image-2159\" alt=\"\" srcset=\"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/ghd.png 1890w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/ghd-300x169.png 300w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/ghd-1024x576.png 1024w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/ghd-768x432.png 768w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/ghd-1536x864.png 1536w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/ghd-18x10.png 18w\" sizes=\"(max-width: 1890px) 100vw, 1890px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<a href=\"#\" class=\"jet-engine-listing-overlay-link\"><\/a><\/div><\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-2162\" data-post-id=\"2162\"  ><div class=\"jet-engine-listing-overlay-wrap jet-popup-target\" data-url=\"#\" data-popup-instance=\"1645\" data-popup-trigger-type=\"click-self\" data-popup-is-jet-engine=\"1\">\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"224\" class=\"elementor elementor-224\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b59a357 e-con-full e-flex e-con e-child\" data-id=\"b59a357\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-afd04b0 elementor-widget elementor-widget-image\" data-id=\"afd04b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/leonardocincinelli.com\/de\/leo-music-design\/popup-wifi\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1890\" height=\"1063\" src=\"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2026\/01\/Popup-wifi-1.png\" class=\"attachment-full size-full wp-image-2164\" alt=\"\" srcset=\"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2026\/01\/Popup-wifi-1.png 1890w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2026\/01\/Popup-wifi-1-300x169.png 300w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2026\/01\/Popup-wifi-1-1024x576.png 1024w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2026\/01\/Popup-wifi-1-768x432.png 768w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2026\/01\/Popup-wifi-1-1536x864.png 1536w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2026\/01\/Popup-wifi-1-18x10.png 18w\" sizes=\"(max-width: 1890px) 100vw, 1890px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<a href=\"#\" class=\"jet-engine-listing-overlay-link\"><\/a><\/div><\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-337\" data-post-id=\"337\"  ><div class=\"jet-engine-listing-overlay-wrap jet-popup-target\" data-url=\"#\" data-popup-instance=\"1645\" data-popup-trigger-type=\"click-self\" data-popup-is-jet-engine=\"1\">\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"224\" class=\"elementor elementor-224\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b59a357 e-con-full e-flex e-con e-child\" data-id=\"b59a357\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-afd04b0 elementor-widget elementor-widget-image\" data-id=\"afd04b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/leonardocincinelli.com\/de\/leo-music-design\/rito-rhymes\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1890\" height=\"1063\" src=\"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/Rito-Rhymes.png\" class=\"attachment-full size-full wp-image-217\" alt=\"\" srcset=\"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/Rito-Rhymes.png 1890w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/Rito-Rhymes-300x169.png 300w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/Rito-Rhymes-1024x576.png 1024w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/Rito-Rhymes-768x432.png 768w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/Rito-Rhymes-1536x864.png 1536w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/Rito-Rhymes-18x10.png 18w\" sizes=\"(max-width: 1890px) 100vw, 1890px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<a href=\"#\" class=\"jet-engine-listing-overlay-link\"><\/a><\/div><\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-336\" data-post-id=\"336\"  ><div class=\"jet-engine-listing-overlay-wrap jet-popup-target\" data-url=\"#\" data-popup-instance=\"1645\" data-popup-trigger-type=\"click-self\" data-popup-is-jet-engine=\"1\">\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"224\" class=\"elementor elementor-224\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b59a357 e-con-full e-flex e-con e-child\" data-id=\"b59a357\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-afd04b0 elementor-widget elementor-widget-image\" data-id=\"afd04b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/leonardocincinelli.com\/de\/leo-music-design\/arenas\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1890\" height=\"1063\" src=\"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/arenas.png\" class=\"attachment-full size-full wp-image-216\" alt=\"\" srcset=\"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/arenas.png 1890w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/arenas-300x169.png 300w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/arenas-1024x576.png 1024w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/arenas-768x432.png 768w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/arenas-1536x864.png 1536w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/arenas-18x10.png 18w\" sizes=\"(max-width: 1890px) 100vw, 1890px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<a href=\"#\" class=\"jet-engine-listing-overlay-link\"><\/a><\/div><\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-334\" data-post-id=\"334\"  ><div class=\"jet-engine-listing-overlay-wrap jet-popup-target\" data-url=\"#\" data-popup-instance=\"1645\" data-popup-trigger-type=\"click-self\" data-popup-is-jet-engine=\"1\">\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"224\" class=\"elementor elementor-224\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b59a357 e-con-full e-flex e-con e-child\" data-id=\"b59a357\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-afd04b0 elementor-widget elementor-widget-image\" data-id=\"afd04b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/leonardocincinelli.com\/de\/leo-music-design\/varchi-di-luce\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1890\" height=\"1063\" src=\"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/03\/francesco.png\" class=\"attachment-full size-full wp-image-1271\" alt=\"\" srcset=\"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/03\/francesco.png 1890w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/03\/francesco-300x169.png 300w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/03\/francesco-1024x576.png 1024w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/03\/francesco-768x432.png 768w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/03\/francesco-1536x864.png 1536w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/03\/francesco-18x10.png 18w\" sizes=\"(max-width: 1890px) 100vw, 1890px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<a href=\"#\" class=\"jet-engine-listing-overlay-link\"><\/a><\/div><\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-333\" data-post-id=\"333\"  ><div class=\"jet-engine-listing-overlay-wrap jet-popup-target\" data-url=\"#\" data-popup-instance=\"1645\" data-popup-trigger-type=\"click-self\" data-popup-is-jet-engine=\"1\">\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"224\" class=\"elementor elementor-224\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b59a357 e-con-full e-flex e-con e-child\" data-id=\"b59a357\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-afd04b0 elementor-widget elementor-widget-image\" data-id=\"afd04b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/leonardocincinelli.com\/de\/leo-music-design\/open-your-mind\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1890\" height=\"1063\" src=\"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/pong.png\" class=\"attachment-full size-full wp-image-215\" alt=\"\" srcset=\"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/pong.png 1890w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/pong-300x169.png 300w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/pong-1024x576.png 1024w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/pong-768x432.png 768w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/pong-1536x864.png 1536w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/pong-18x10.png 18w\" sizes=\"(max-width: 1890px) 100vw, 1890px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<a href=\"#\" class=\"jet-engine-listing-overlay-link\"><\/a><\/div><\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-332\" data-post-id=\"332\"  ><div class=\"jet-engine-listing-overlay-wrap jet-popup-target\" data-url=\"#\" data-popup-instance=\"1645\" data-popup-trigger-type=\"click-self\" data-popup-is-jet-engine=\"1\">\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"224\" class=\"elementor elementor-224\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b59a357 e-con-full e-flex e-con e-child\" data-id=\"b59a357\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-afd04b0 elementor-widget elementor-widget-image\" data-id=\"afd04b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/leonardocincinelli.com\/de\/leo-music-design\/art-eria\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1890\" height=\"1063\" src=\"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/03\/arteria2.png\" class=\"attachment-full size-full wp-image-1270\" alt=\"\" srcset=\"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/03\/arteria2.png 1890w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/03\/arteria2-300x169.png 300w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/03\/arteria2-1024x576.png 1024w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/03\/arteria2-768x432.png 768w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/03\/arteria2-1536x864.png 1536w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/03\/arteria2-18x10.png 18w\" sizes=\"(max-width: 1890px) 100vw, 1890px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<a href=\"#\" class=\"jet-engine-listing-overlay-link\"><\/a><\/div><\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-331\" data-post-id=\"331\"  ><div class=\"jet-engine-listing-overlay-wrap jet-popup-target\" data-url=\"#\" data-popup-instance=\"1645\" data-popup-trigger-type=\"click-self\" data-popup-is-jet-engine=\"1\">\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"224\" class=\"elementor elementor-224\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b59a357 e-con-full e-flex e-con e-child\" data-id=\"b59a357\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-afd04b0 elementor-widget elementor-widget-image\" data-id=\"afd04b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/leonardocincinelli.com\/de\/leo-music-design\/physical-momentum-project\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1890\" height=\"1063\" src=\"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/03\/physical.png\" class=\"attachment-full size-full wp-image-1273\" alt=\"\" srcset=\"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/03\/physical.png 1890w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/03\/physical-300x169.png 300w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/03\/physical-1024x576.png 1024w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/03\/physical-768x432.png 768w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/03\/physical-1536x864.png 1536w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/03\/physical-18x10.png 18w\" sizes=\"(max-width: 1890px) 100vw, 1890px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<a href=\"#\" class=\"jet-engine-listing-overlay-link\"><\/a><\/div><\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-330\" data-post-id=\"330\"  ><div class=\"jet-engine-listing-overlay-wrap jet-popup-target\" data-url=\"#\" data-popup-instance=\"1645\" data-popup-trigger-type=\"click-self\" data-popup-is-jet-engine=\"1\">\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"224\" class=\"elementor elementor-224\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b59a357 e-con-full e-flex e-con e-child\" data-id=\"b59a357\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-afd04b0 elementor-widget elementor-widget-image\" data-id=\"afd04b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/leonardocincinelli.com\/de\/leo-music-design\/vichy\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1890\" height=\"1063\" src=\"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/03\/vichy.png\" class=\"attachment-full size-full wp-image-1276\" alt=\"\" srcset=\"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/03\/vichy.png 1890w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/03\/vichy-300x169.png 300w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/03\/vichy-1024x576.png 1024w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/03\/vichy-768x432.png 768w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/03\/vichy-1536x864.png 1536w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/03\/vichy-18x10.png 18w\" sizes=\"(max-width: 1890px) 100vw, 1890px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<a href=\"#\" class=\"jet-engine-listing-overlay-link\"><\/a><\/div><\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-329\" data-post-id=\"329\"  ><div class=\"jet-engine-listing-overlay-wrap jet-popup-target\" data-url=\"#\" data-popup-instance=\"1645\" data-popup-trigger-type=\"click-self\" data-popup-is-jet-engine=\"1\">\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"224\" class=\"elementor elementor-224\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b59a357 e-con-full e-flex e-con e-child\" data-id=\"b59a357\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-afd04b0 elementor-widget elementor-widget-image\" data-id=\"afd04b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/leonardocincinelli.com\/de\/leo-music-design\/masters\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1890\" height=\"1063\" src=\"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/03\/masters.png\" class=\"attachment-full size-full wp-image-1275\" alt=\"\" srcset=\"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/03\/masters.png 1890w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/03\/masters-300x169.png 300w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/03\/masters-1024x576.png 1024w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/03\/masters-768x432.png 768w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/03\/masters-1536x864.png 1536w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/03\/masters-18x10.png 18w\" sizes=\"(max-width: 1890px) 100vw, 1890px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<a href=\"#\" class=\"jet-engine-listing-overlay-link\"><\/a><\/div><\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-328\" data-post-id=\"328\"  ><div class=\"jet-engine-listing-overlay-wrap jet-popup-target\" data-url=\"#\" data-popup-instance=\"1645\" data-popup-trigger-type=\"click-self\" data-popup-is-jet-engine=\"1\">\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"224\" class=\"elementor elementor-224\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b59a357 e-con-full e-flex e-con e-child\" data-id=\"b59a357\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-afd04b0 elementor-widget elementor-widget-image\" data-id=\"afd04b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/leonardocincinelli.com\/de\/leo-music-design\/palacio-del-flamenco\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1890\" height=\"1063\" src=\"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/palacio-del-flamenco.png\" class=\"attachment-full size-full wp-image-210\" alt=\"\" srcset=\"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/palacio-del-flamenco.png 1890w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/palacio-del-flamenco-300x169.png 300w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/palacio-del-flamenco-1024x576.png 1024w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/palacio-del-flamenco-768x432.png 768w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/palacio-del-flamenco-1536x864.png 1536w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/palacio-del-flamenco-18x10.png 18w\" sizes=\"(max-width: 1890px) 100vw, 1890px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<a href=\"#\" class=\"jet-engine-listing-overlay-link\"><\/a><\/div><\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-327\" data-post-id=\"327\"  ><div class=\"jet-engine-listing-overlay-wrap jet-popup-target\" data-url=\"#\" data-popup-instance=\"1645\" data-popup-trigger-type=\"click-self\" data-popup-is-jet-engine=\"1\">\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"224\" class=\"elementor elementor-224\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b59a357 e-con-full e-flex e-con e-child\" data-id=\"b59a357\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-afd04b0 elementor-widget elementor-widget-image\" data-id=\"afd04b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/leonardocincinelli.com\/de\/leo-music-design\/tous\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1890\" height=\"1063\" src=\"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/Tous.png\" class=\"attachment-full size-full wp-image-209\" alt=\"\" srcset=\"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/Tous.png 1890w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/Tous-300x169.png 300w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/Tous-1024x576.png 1024w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/Tous-768x432.png 768w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/Tous-1536x864.png 1536w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/Tous-18x10.png 18w\" sizes=\"(max-width: 1890px) 100vw, 1890px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<a href=\"#\" class=\"jet-engine-listing-overlay-link\"><\/a><\/div><\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-238\" data-post-id=\"238\"  ><div class=\"jet-engine-listing-overlay-wrap jet-popup-target\" data-url=\"#\" data-popup-instance=\"1645\" data-popup-trigger-type=\"click-self\" data-popup-is-jet-engine=\"1\">\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"224\" class=\"elementor elementor-224\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b59a357 e-con-full e-flex e-con e-child\" data-id=\"b59a357\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-afd04b0 elementor-widget elementor-widget-image\" data-id=\"afd04b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/leonardocincinelli.com\/de\/leo-music-design\/hozho\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1890\" height=\"1063\" src=\"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/hozho.png\" class=\"attachment-full size-full wp-image-208\" alt=\"\" srcset=\"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/hozho.png 1890w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/hozho-300x169.png 300w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/hozho-1024x576.png 1024w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/hozho-768x432.png 768w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/hozho-1536x864.png 1536w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/hozho-18x10.png 18w\" sizes=\"(max-width: 1890px) 100vw, 1890px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<a href=\"#\" class=\"jet-engine-listing-overlay-link\"><\/a><\/div><\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-237\" data-post-id=\"237\"  ><div class=\"jet-engine-listing-overlay-wrap jet-popup-target\" data-url=\"#\" data-popup-instance=\"1645\" data-popup-trigger-type=\"click-self\" data-popup-is-jet-engine=\"1\">\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"224\" class=\"elementor elementor-224\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b59a357 e-con-full e-flex e-con e-child\" data-id=\"b59a357\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-afd04b0 elementor-widget elementor-widget-image\" data-id=\"afd04b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/leonardocincinelli.com\/de\/leo-music-design\/la-ciutat-inventada\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1890\" height=\"1063\" src=\"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/la-ciutat_inventada_v6.png\" class=\"attachment-full size-full wp-image-206\" alt=\"\" srcset=\"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/la-ciutat_inventada_v6.png 1890w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/la-ciutat_inventada_v6-300x169.png 300w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/la-ciutat_inventada_v6-1024x576.png 1024w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/la-ciutat_inventada_v6-768x432.png 768w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/la-ciutat_inventada_v6-1536x864.png 1536w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/la-ciutat_inventada_v6-18x10.png 18w\" sizes=\"(max-width: 1890px) 100vw, 1890px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<a href=\"#\" class=\"jet-engine-listing-overlay-link\"><\/a><\/div><\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-222\" data-post-id=\"222\"  ><div class=\"jet-engine-listing-overlay-wrap jet-popup-target\" data-url=\"#\" data-popup-instance=\"1645\" data-popup-trigger-type=\"click-self\" data-popup-is-jet-engine=\"1\">\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"224\" class=\"elementor elementor-224\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b59a357 e-con-full e-flex e-con e-child\" data-id=\"b59a357\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-afd04b0 elementor-widget elementor-widget-image\" data-id=\"afd04b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/leonardocincinelli.com\/de\/leo-music-design\/earth-sutra\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1890\" height=\"1063\" src=\"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/earth-sutra.png\" class=\"attachment-full size-full wp-image-199\" alt=\"\" srcset=\"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/earth-sutra.png 1890w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/earth-sutra-300x169.png 300w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/earth-sutra-1024x576.png 1024w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/earth-sutra-768x432.png 768w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/earth-sutra-1536x864.png 1536w, https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/earth-sutra-18x10.png 18w\" sizes=\"(max-width: 1890px) 100vw, 1890px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<a href=\"#\" class=\"jet-engine-listing-overlay-link\"><\/a><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Eine Auswahl von Werken, die f\u00fcr Filme, Werbespots und audiovisuelle Installationen geschaffen wurden.<\/p>","protected":false},"author":8,"featured_media":0,"parent":0,"menu_order":3,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-189","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Music for media - Leonardo Cincinelli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leonardocincinelli.com\/de\/music-for-media-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Music for media - Leonardo Cincinelli\" \/>\n<meta property=\"og:description\" content=\"A selection of works created for films, commercials and audiovisual installations.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leonardocincinelli.com\/de\/music-for-media-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Leonardo Cincinelli\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-23T09:36:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/03\/home-2-819x1024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"819\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/leonardocincinelli.com\\\/music-for-media-2\\\/\",\"url\":\"https:\\\/\\\/leonardocincinelli.com\\\/music-for-media-2\\\/\",\"name\":\"Music for media - Leonardo Cincinelli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leonardocincinelli.com\\\/#website\"},\"datePublished\":\"2025-02-24T13:32:33+00:00\",\"dateModified\":\"2026-02-23T09:36:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leonardocincinelli.com\\\/music-for-media-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/leonardocincinelli.com\\\/music-for-media-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leonardocincinelli.com\\\/music-for-media-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/leonardocincinelli.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Music for media\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leonardocincinelli.com\\\/#website\",\"url\":\"https:\\\/\\\/leonardocincinelli.com\\\/\",\"name\":\"Leonardo Cincinelli\",\"description\":\"Music Designer\",\"publisher\":{\"@id\":\"https:\\\/\\\/leonardocincinelli.com\\\/#\\\/schema\\\/person\\\/4e8f938b0ba55bdd58344f52ffb3acf1\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leonardocincinelli.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/leonardocincinelli.com\\\/#\\\/schema\\\/person\\\/4e8f938b0ba55bdd58344f52ffb3acf1\",\"name\":\"Leonardo Cincinelli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/leonardocincinelli.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/LogoWEB-e1740150454111.png\",\"url\":\"https:\\\/\\\/leonardocincinelli.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/LogoWEB-e1740150454111.png\",\"contentUrl\":\"https:\\\/\\\/leonardocincinelli.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/LogoWEB-e1740150454111.png\",\"width\":500,\"height\":385,\"caption\":\"Leonardo Cincinelli\"},\"logo\":{\"@id\":\"https:\\\/\\\/leonardocincinelli.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/LogoWEB-e1740150454111.png\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Music for media - Leonardo Cincinelli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leonardocincinelli.com\/de\/music-for-media-2\/","og_locale":"de_DE","og_type":"article","og_title":"Music for media - Leonardo Cincinelli","og_description":"A selection of works created for films, commercials and audiovisual installations.","og_url":"https:\/\/leonardocincinelli.com\/de\/music-for-media-2\/","og_site_name":"Leonardo Cincinelli","article_modified_time":"2026-02-23T09:36:12+00:00","og_image":[{"width":819,"height":1024,"url":"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/03\/home-2-819x1024.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/leonardocincinelli.com\/music-for-media-2\/","url":"https:\/\/leonardocincinelli.com\/music-for-media-2\/","name":"Music for media - Leonardo Cincinelli","isPartOf":{"@id":"https:\/\/leonardocincinelli.com\/#website"},"datePublished":"2025-02-24T13:32:33+00:00","dateModified":"2026-02-23T09:36:12+00:00","breadcrumb":{"@id":"https:\/\/leonardocincinelli.com\/music-for-media-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leonardocincinelli.com\/music-for-media-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/leonardocincinelli.com\/music-for-media-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/leonardocincinelli.com\/"},{"@type":"ListItem","position":2,"name":"Music for media"}]},{"@type":"WebSite","@id":"https:\/\/leonardocincinelli.com\/#website","url":"https:\/\/leonardocincinelli.com\/","name":"Leonardo Cincinelli","description":"Musik-Designer","publisher":{"@id":"https:\/\/leonardocincinelli.com\/#\/schema\/person\/4e8f938b0ba55bdd58344f52ffb3acf1"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leonardocincinelli.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/leonardocincinelli.com\/#\/schema\/person\/4e8f938b0ba55bdd58344f52ffb3acf1","name":"Leonardo Cincinelli","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/01\/LogoWEB-e1740150454111.png","url":"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/01\/LogoWEB-e1740150454111.png","contentUrl":"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/01\/LogoWEB-e1740150454111.png","width":500,"height":385,"caption":"Leonardo Cincinelli"},"logo":{"@id":"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/01\/LogoWEB-e1740150454111.png"}}]}},"_hostinger_reach_plugin_has_subscription_block":false,"_hostinger_reach_plugin_is_elementor":false,"_links":{"self":[{"href":"https:\/\/leonardocincinelli.com\/de\/wp-json\/wp\/v2\/pages\/189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leonardocincinelli.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/leonardocincinelli.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/leonardocincinelli.com\/de\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/leonardocincinelli.com\/de\/wp-json\/wp\/v2\/comments?post=189"}],"version-history":[{"count":50,"href":"https:\/\/leonardocincinelli.com\/de\/wp-json\/wp\/v2\/pages\/189\/revisions"}],"predecessor-version":[{"id":2185,"href":"https:\/\/leonardocincinelli.com\/de\/wp-json\/wp\/v2\/pages\/189\/revisions\/2185"}],"wp:attachment":[{"href":"https:\/\/leonardocincinelli.com\/de\/wp-json\/wp\/v2\/media?parent=189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}