{"id":328,"date":"2025-02-25T16:45:56","date_gmt":"2025-02-25T15:45:56","guid":{"rendered":"https:\/\/leonardocincinelli.com\/?post_type=leo-music-design&#038;p=328"},"modified":"2025-03-27T18:13:11","modified_gmt":"2025-03-27T17:13:11","slug":"palacio-del-flamenco","status":"publish","type":"leo-music-design","link":"https:\/\/leonardocincinelli.com\/pt\/leo-music-design\/palacio-del-flamenco\/","title":{"rendered":"Pal\u00e1cio do Flamenco"},"featured_media":210,"template":"","class_list":["post-328","leo-music-design","type-leo-music-design","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Palacio del Flamenco - Leonardo Cincinelli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leonardocincinelli.com\/pt\/leo-music-design\/palacio-del-flamenco\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Palacio del Flamenco - Leonardo Cincinelli\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leonardocincinelli.com\/pt\/leo-music-design\/palacio-del-flamenco\/\" \/>\n<meta property=\"og:site_name\" content=\"Leonardo Cincinelli\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-27T17:13:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/palacio-del-flamenco.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1890\" \/>\n\t<meta property=\"og:image:height\" content=\"1063\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/leonardocincinelli.com\\\/leo-music-design\\\/palacio-del-flamenco\\\/\",\"url\":\"https:\\\/\\\/leonardocincinelli.com\\\/leo-music-design\\\/palacio-del-flamenco\\\/\",\"name\":\"Palacio del Flamenco - Leonardo Cincinelli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leonardocincinelli.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/leonardocincinelli.com\\\/leo-music-design\\\/palacio-del-flamenco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/leonardocincinelli.com\\\/leo-music-design\\\/palacio-del-flamenco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leonardocincinelli.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/palacio-del-flamenco.png\",\"datePublished\":\"2025-02-25T15:45:56+00:00\",\"dateModified\":\"2025-03-27T17:13:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leonardocincinelli.com\\\/leo-music-design\\\/palacio-del-flamenco\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/leonardocincinelli.com\\\/leo-music-design\\\/palacio-del-flamenco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/leonardocincinelli.com\\\/leo-music-design\\\/palacio-del-flamenco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/leonardocincinelli.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/palacio-del-flamenco.png\",\"contentUrl\":\"https:\\\/\\\/leonardocincinelli.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/palacio-del-flamenco.png\",\"width\":1890,\"height\":1063},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leonardocincinelli.com\\\/leo-music-design\\\/palacio-del-flamenco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/leonardocincinelli.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Music for Media\",\"item\":\"https:\\\/\\\/leonardocincinelli.com\\\/leo-music-design\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Palacio del Flamenco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leonardocincinelli.com\\\/#website\",\"url\":\"https:\\\/\\\/leonardocincinelli.com\\\/\",\"name\":\"Leonardo Cincinelli\",\"description\":\"Music Designer\",\"publisher\":{\"@id\":\"https:\\\/\\\/leonardocincinelli.com\\\/#\\\/schema\\\/person\\\/4e8f938b0ba55bdd58344f52ffb3acf1\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leonardocincinelli.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/leonardocincinelli.com\\\/#\\\/schema\\\/person\\\/4e8f938b0ba55bdd58344f52ffb3acf1\",\"name\":\"Leonardo Cincinelli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/leonardocincinelli.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/LogoWEB-e1740150454111.png\",\"url\":\"https:\\\/\\\/leonardocincinelli.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/LogoWEB-e1740150454111.png\",\"contentUrl\":\"https:\\\/\\\/leonardocincinelli.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/LogoWEB-e1740150454111.png\",\"width\":500,\"height\":385,\"caption\":\"Leonardo Cincinelli\"},\"logo\":{\"@id\":\"https:\\\/\\\/leonardocincinelli.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/LogoWEB-e1740150454111.png\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Palacio del Flamenco - Leonardo Cincinelli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leonardocincinelli.com\/pt\/leo-music-design\/palacio-del-flamenco\/","og_locale":"pt_PT","og_type":"article","og_title":"Palacio del Flamenco - Leonardo Cincinelli","og_url":"https:\/\/leonardocincinelli.com\/pt\/leo-music-design\/palacio-del-flamenco\/","og_site_name":"Leonardo Cincinelli","article_modified_time":"2025-03-27T17:13:11+00:00","og_image":[{"width":1890,"height":1063,"url":"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/palacio-del-flamenco.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/leonardocincinelli.com\/leo-music-design\/palacio-del-flamenco\/","url":"https:\/\/leonardocincinelli.com\/leo-music-design\/palacio-del-flamenco\/","name":"Palacio del Flamenco - Leonardo Cincinelli","isPartOf":{"@id":"https:\/\/leonardocincinelli.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/leonardocincinelli.com\/leo-music-design\/palacio-del-flamenco\/#primaryimage"},"image":{"@id":"https:\/\/leonardocincinelli.com\/leo-music-design\/palacio-del-flamenco\/#primaryimage"},"thumbnailUrl":"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/palacio-del-flamenco.png","datePublished":"2025-02-25T15:45:56+00:00","dateModified":"2025-03-27T17:13:11+00:00","breadcrumb":{"@id":"https:\/\/leonardocincinelli.com\/leo-music-design\/palacio-del-flamenco\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leonardocincinelli.com\/leo-music-design\/palacio-del-flamenco\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/leonardocincinelli.com\/leo-music-design\/palacio-del-flamenco\/#primaryimage","url":"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/palacio-del-flamenco.png","contentUrl":"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/02\/palacio-del-flamenco.png","width":1890,"height":1063},{"@type":"BreadcrumbList","@id":"https:\/\/leonardocincinelli.com\/leo-music-design\/palacio-del-flamenco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/leonardocincinelli.com\/"},{"@type":"ListItem","position":2,"name":"Music for Media","item":"https:\/\/leonardocincinelli.com\/leo-music-design\/"},{"@type":"ListItem","position":3,"name":"Palacio del Flamenco"}]},{"@type":"WebSite","@id":"https:\/\/leonardocincinelli.com\/#website","url":"https:\/\/leonardocincinelli.com\/","name":"Leonardo Cincinelli","description":"Designer de m\u00fasica","publisher":{"@id":"https:\/\/leonardocincinelli.com\/#\/schema\/person\/4e8f938b0ba55bdd58344f52ffb3acf1"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leonardocincinelli.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":["Person","Organization"],"@id":"https:\/\/leonardocincinelli.com\/#\/schema\/person\/4e8f938b0ba55bdd58344f52ffb3acf1","name":"Leonardo Cincinelli","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/01\/LogoWEB-e1740150454111.png","url":"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/01\/LogoWEB-e1740150454111.png","contentUrl":"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/01\/LogoWEB-e1740150454111.png","width":500,"height":385,"caption":"Leonardo Cincinelli"},"logo":{"@id":"https:\/\/leonardocincinelli.com\/wp-content\/uploads\/2025\/01\/LogoWEB-e1740150454111.png"}}]}},"_links":{"self":[{"href":"https:\/\/leonardocincinelli.com\/pt\/wp-json\/wp\/v2\/leo-music-design\/328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leonardocincinelli.com\/pt\/wp-json\/wp\/v2\/leo-music-design"}],"about":[{"href":"https:\/\/leonardocincinelli.com\/pt\/wp-json\/wp\/v2\/types\/leo-music-design"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leonardocincinelli.com\/pt\/wp-json\/wp\/v2\/media\/210"}],"wp:attachment":[{"href":"https:\/\/leonardocincinelli.com\/pt\/wp-json\/wp\/v2\/media?parent=328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}